{"id":2878,"date":"2023-11-10T12:04:40","date_gmt":"2023-11-10T12:04:40","guid":{"rendered":"http:\/\/ara.dev.crehaz.qwair.com\/?p=2878"},"modified":"2024-02-14T07:46:14","modified_gmt":"2024-02-14T07:46:14","slug":"hosteleria-espana-celebra-la-xvii-gala-de-los-premios-nacionales-de-hosteleria","status":"publish","type":"post","link":"https:\/\/www.araalicante.com\/en\/hosteleria-espana-celebra-la-xvii-gala-de-los-premios-nacionales-de-hosteleria\/","title":{"rendered":"Hosteler\u00eda Espa\u00f1a celebra la XVII Gala de los Premios Nacionales de Hosteler\u00eda"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"has-x-large-font-size wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\">Mar\u00eda Jos\u00e9 San Rom\u00e1n y el Restaurante El Xato han sido nuestra mejor representaci\u00f3n en estos premios que, como cada a\u00f1o, re\u00fanen a los mejores profesionales del sector.<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Madrid, 7 de noviembre de 2023<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">HOSTELER\u00cdA DE ESPA\u00d1A ha celebrado esta ma\u00f1ana la gala de entrega de la XVII edici\u00f3n de los Premios Nacionales de Hosteler\u00eda, en el Caixa Forum de Madrid.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta edici\u00f3n 2023 incorpora, por primera vez, un premio a la sala como reconocimiento a todos los profesionales que se encargan de que la experiencia del cliente sea un \u00e9xito gracias a su profesionalidad y la excelencia en el desarrollo de su trabajo. El Restaurante Zalaca\u00edn de Madrid inaugura este galard\u00f3n especial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Los premios homenajean, un a\u00f1o m\u00e1s, el trabajo, compromiso y profesionalidad de dieciocho establecimientos, empresas, instituciones y personas que han destacado en aspectos claves como la innovaci\u00f3n, la sostenibilidad, el apoyo a la cultura, el compromiso con las personas con discapacidad o la responsabilidad social, entre otros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente de Hosteler\u00eda de Espa\u00f1a, Jos\u00e9 Luis Yzuel, quiso dejar claro en el cierre de la gala que \u201cla hosteler\u00eda est\u00e1 viviendo un buen a\u00f1o con datos r\u00e9cord de empleo, 100.000 empleos m\u00e1s, pero sabemos que hay nubarrones en el camino, tenemos un ticket medio m\u00e1s bajo y hay un descenso de la rentabilidad\u201d a pesar de esto Yzuel asegur\u00f3 que \u201cnos mantenemos optimistas porque sabemos que mientras haya clientes hay soluciones\u201d.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado, el presidente de Hosteler\u00eda de Espa\u00f1a destac\u00f3 que \u201ctenemos muchos deberes por hacer, continuar trabajando por el reconocimiento de nuestra profesi\u00f3n, en la representaci\u00f3n del sector, con solvencia y firmeza, y hacerlo codo con codo con las asociaciones, las administraciones, y la cadena de valor, a trav\u00e9s de un mont\u00f3n de proyectos en materia, por ejemplo, de sostenibilidad, formaci\u00f3n y digitalizaci\u00f3n\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Todos los premiados son referentes para el sector tanto por su buen hacer profesional como por representar la importancia del personal de sala o los clientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre ellos hemos contado con los premiados M\u00aa Jos\u00e9 San Rom\u00e1n y El Xato, compa\u00f1eros y m\u00e1ximos representantes de la gastronom\u00eda alicantina.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00aa Jos\u00e9 San Rom\u00e1n ha sido galardonada con el \u00abPremio a la persona por su contribuci\u00f3n a la mejora del sector\u00bb, por su fuerte compromiso con la cultura gastron\u00f3mica, su labor para poner en valor el trabajo de las mujeres en la gastronom\u00eda y su constante formaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Xato ha sido galardonado con \u00abPremio a la empresa hostelera destacada en la promoci\u00f3n de la cultura y la gastronom\u00eda espa\u00f1ola\u00bb, poniendo en valor un negocio familiar que cuenta con m\u00e1s de 108 a\u00f1os de historia y cinco generaciones a sus espaldas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Mar\u00eda Jos\u00e9 San Rom\u00e1n y el Restaurante El Xato han sido nuestra<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":19,"featured_media":2879,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[],"class_list":["post-2878","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-restauracion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hosteler\u00eda Espa\u00f1a celebra la XVII Gala de los Premios Nacionales de Hosteler\u00eda - ARA | Asociaci\u00f3n de Restaurantes Alicante<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.araalicante.com\/en\/hosteleria-espana-celebra-la-xvii-gala-de-los-premios-nacionales-de-hosteleria\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hosteler\u00eda Espa\u00f1a celebra la XVII Gala de los Premios Nacionales de Hosteler\u00eda - ARA | Asociaci\u00f3n de Restaurantes Alicante\" \/>\n<meta property=\"og:description\" content=\"Mar\u00eda Jos\u00e9 San Rom\u00e1n y el Restaurante El Xato han sido nuestra [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.araalicante.com\/en\/hosteleria-espana-celebra-la-xvii-gala-de-los-premios-nacionales-de-hosteleria\/\" \/>\n<meta property=\"og:site_name\" content=\"ARA | Asociaci\u00f3n de Restaurantes Alicante\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Ararestaurantesalicante\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-10T12:04:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-14T07:46:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.araalicante.com\/wp-content\/uploads\/2023\/11\/Premios-Hostele.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"547\" \/>\n\t<meta property=\"og:image:height\" content=\"368\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maria Jose Anguita Garc\u00eda\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maria Jose Anguita Garc\u00eda\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.araalicante.com\\\/hosteleria-espana-celebra-la-xvii-gala-de-los-premios-nacionales-de-hosteleria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.araalicante.com\\\/hosteleria-espana-celebra-la-xvii-gala-de-los-premios-nacionales-de-hosteleria\\\/\"},\"author\":{\"name\":\"Maria Jose Anguita Garc\u00eda\",\"@id\":\"https:\\\/\\\/www.araalicante.com\\\/#\\\/schema\\\/person\\\/e812fee62b3ce0c0ebca64fd5be08d67\"},\"headline\":\"Hosteler\u00eda Espa\u00f1a celebra la XVII Gala de los Premios Nacionales de Hosteler\u00eda\",\"datePublished\":\"2023-11-10T12:04:40+00:00\",\"dateModified\":\"2024-02-14T07:46:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.araalicante.com\\\/hosteleria-espana-celebra-la-xvii-gala-de-los-premios-nacionales-de-hosteleria\\\/\"},\"wordCount\":490,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.araalicante.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.araalicante.com\\\/hosteleria-espana-celebra-la-xvii-gala-de-los-premios-nacionales-de-hosteleria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.araalicante.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Premios-Hostele.jpeg\",\"articleSection\":[\"ACTUALIDAD RESTAURACI\u00d3N\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.araalicante.com\\\/hosteleria-espana-celebra-la-xvii-gala-de-los-premios-nacionales-de-hosteleria\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.araalicante.com\\\/hosteleria-espana-celebra-la-xvii-gala-de-los-premios-nacionales-de-hosteleria\\\/\",\"url\":\"https:\\\/\\\/www.araalicante.com\\\/hosteleria-espana-celebra-la-xvii-gala-de-los-premios-nacionales-de-hosteleria\\\/\",\"name\":\"Hosteler\u00eda Espa\u00f1a celebra la XVII Gala de los Premios Nacionales de Hosteler\u00eda - ARA | Asociaci\u00f3n de Restaurantes Alicante\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.araalicante.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.araalicante.com\\\/hosteleria-espana-celebra-la-xvii-gala-de-los-premios-nacionales-de-hosteleria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.araalicante.com\\\/hosteleria-espana-celebra-la-xvii-gala-de-los-premios-nacionales-de-hosteleria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.araalicante.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Premios-Hostele.jpeg\",\"datePublished\":\"2023-11-10T12:04:40+00:00\",\"dateModified\":\"2024-02-14T07:46:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.araalicante.com\\\/hosteleria-espana-celebra-la-xvii-gala-de-los-premios-nacionales-de-hosteleria\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.araalicante.com\\\/hosteleria-espana-celebra-la-xvii-gala-de-los-premios-nacionales-de-hosteleria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.araalicante.com\\\/hosteleria-espana-celebra-la-xvii-gala-de-los-premios-nacionales-de-hosteleria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.araalicante.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Premios-Hostele.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.araalicante.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Premios-Hostele.jpeg\",\"width\":547,\"height\":368},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.araalicante.com\\\/hosteleria-espana-celebra-la-xvii-gala-de-los-premios-nacionales-de-hosteleria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.araalicante.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hosteler\u00eda Espa\u00f1a celebra la XVII Gala de los Premios Nacionales de Hosteler\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.araalicante.com\\\/#website\",\"url\":\"https:\\\/\\\/www.araalicante.com\\\/\",\"name\":\"ARA | Asociaci\u00f3n de Restaurantes Alicante\",\"description\":\"Producto local, restauraci\u00f3n de calidad en Alicante y su provincia\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.araalicante.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.araalicante.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.araalicante.com\\\/#organization\",\"name\":\"ARA | Asociaci\u00f3n de Restaurantes Alicante\",\"url\":\"https:\\\/\\\/www.araalicante.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.araalicante.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.araalicante.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logoara.png\",\"contentUrl\":\"https:\\\/\\\/www.araalicante.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logoara.png\",\"width\":400,\"height\":85,\"caption\":\"ARA | Asociaci\u00f3n de Restaurantes Alicante\"},\"image\":{\"@id\":\"https:\\\/\\\/www.araalicante.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Ararestaurantesalicante\",\"https:\\\/\\\/www.instagram.com\\\/ararestaurantesalicante\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.araalicante.com\\\/#\\\/schema\\\/person\\\/e812fee62b3ce0c0ebca64fd5be08d67\",\"name\":\"Maria Jose Anguita Garc\u00eda\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/717304dec3288ef41af7c91b6a8cecd0c5ac16a99dc419d6a059e8ac1557c4de?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/717304dec3288ef41af7c91b6a8cecd0c5ac16a99dc419d6a059e8ac1557c4de?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/717304dec3288ef41af7c91b6a8cecd0c5ac16a99dc419d6a059e8ac1557c4de?s=96&d=mm&r=g\",\"caption\":\"Maria Jose Anguita Garc\u00eda\"},\"url\":\"https:\\\/\\\/www.araalicante.com\\\/en\\\/author\\\/maria-jose\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hosteler\u00eda Espa\u00f1a celebra la XVII Gala de los Premios Nacionales de Hosteler\u00eda - ARA | Asociaci\u00f3n de Restaurantes Alicante","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.araalicante.com\/en\/hosteleria-espana-celebra-la-xvii-gala-de-los-premios-nacionales-de-hosteleria\/","og_locale":"en_GB","og_type":"article","og_title":"Hosteler\u00eda Espa\u00f1a celebra la XVII Gala de los Premios Nacionales de Hosteler\u00eda - ARA | Asociaci\u00f3n de Restaurantes Alicante","og_description":"Mar\u00eda Jos\u00e9 San Rom\u00e1n y el Restaurante El Xato han sido nuestra [\u2026]","og_url":"https:\/\/www.araalicante.com\/en\/hosteleria-espana-celebra-la-xvii-gala-de-los-premios-nacionales-de-hosteleria\/","og_site_name":"ARA | Asociaci\u00f3n de Restaurantes Alicante","article_publisher":"https:\/\/www.facebook.com\/Ararestaurantesalicante","article_published_time":"2023-11-10T12:04:40+00:00","article_modified_time":"2024-02-14T07:46:14+00:00","og_image":[{"width":547,"height":368,"url":"https:\/\/www.araalicante.com\/wp-content\/uploads\/2023\/11\/Premios-Hostele.jpeg","type":"image\/jpeg"}],"author":"Maria Jose Anguita Garc\u00eda","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Maria Jose Anguita Garc\u00eda","Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.araalicante.com\/hosteleria-espana-celebra-la-xvii-gala-de-los-premios-nacionales-de-hosteleria\/#article","isPartOf":{"@id":"https:\/\/www.araalicante.com\/hosteleria-espana-celebra-la-xvii-gala-de-los-premios-nacionales-de-hosteleria\/"},"author":{"name":"Maria Jose Anguita Garc\u00eda","@id":"https:\/\/www.araalicante.com\/#\/schema\/person\/e812fee62b3ce0c0ebca64fd5be08d67"},"headline":"Hosteler\u00eda Espa\u00f1a celebra la XVII Gala de los Premios Nacionales de Hosteler\u00eda","datePublished":"2023-11-10T12:04:40+00:00","dateModified":"2024-02-14T07:46:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.araalicante.com\/hosteleria-espana-celebra-la-xvii-gala-de-los-premios-nacionales-de-hosteleria\/"},"wordCount":490,"commentCount":0,"publisher":{"@id":"https:\/\/www.araalicante.com\/#organization"},"image":{"@id":"https:\/\/www.araalicante.com\/hosteleria-espana-celebra-la-xvii-gala-de-los-premios-nacionales-de-hosteleria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.araalicante.com\/wp-content\/uploads\/2023\/11\/Premios-Hostele.jpeg","articleSection":["ACTUALIDAD RESTAURACI\u00d3N"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.araalicante.com\/hosteleria-espana-celebra-la-xvii-gala-de-los-premios-nacionales-de-hosteleria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.araalicante.com\/hosteleria-espana-celebra-la-xvii-gala-de-los-premios-nacionales-de-hosteleria\/","url":"https:\/\/www.araalicante.com\/hosteleria-espana-celebra-la-xvii-gala-de-los-premios-nacionales-de-hosteleria\/","name":"Hosteler\u00eda Espa\u00f1a celebra la XVII Gala de los Premios Nacionales de Hosteler\u00eda - ARA | Asociaci\u00f3n de Restaurantes Alicante","isPartOf":{"@id":"https:\/\/www.araalicante.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.araalicante.com\/hosteleria-espana-celebra-la-xvii-gala-de-los-premios-nacionales-de-hosteleria\/#primaryimage"},"image":{"@id":"https:\/\/www.araalicante.com\/hosteleria-espana-celebra-la-xvii-gala-de-los-premios-nacionales-de-hosteleria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.araalicante.com\/wp-content\/uploads\/2023\/11\/Premios-Hostele.jpeg","datePublished":"2023-11-10T12:04:40+00:00","dateModified":"2024-02-14T07:46:14+00:00","breadcrumb":{"@id":"https:\/\/www.araalicante.com\/hosteleria-espana-celebra-la-xvii-gala-de-los-premios-nacionales-de-hosteleria\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.araalicante.com\/hosteleria-espana-celebra-la-xvii-gala-de-los-premios-nacionales-de-hosteleria\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.araalicante.com\/hosteleria-espana-celebra-la-xvii-gala-de-los-premios-nacionales-de-hosteleria\/#primaryimage","url":"https:\/\/www.araalicante.com\/wp-content\/uploads\/2023\/11\/Premios-Hostele.jpeg","contentUrl":"https:\/\/www.araalicante.com\/wp-content\/uploads\/2023\/11\/Premios-Hostele.jpeg","width":547,"height":368},{"@type":"BreadcrumbList","@id":"https:\/\/www.araalicante.com\/hosteleria-espana-celebra-la-xvii-gala-de-los-premios-nacionales-de-hosteleria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.araalicante.com\/"},{"@type":"ListItem","position":2,"name":"Hosteler\u00eda Espa\u00f1a celebra la XVII Gala de los Premios Nacionales de Hosteler\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/www.araalicante.com\/#website","url":"https:\/\/www.araalicante.com\/","name":"ARA | Asociaci\u00f3n de Restaurantes Alicante","description":"Producto local, restauraci\u00f3n de calidad en Alicante y su provincia","publisher":{"@id":"https:\/\/www.araalicante.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.araalicante.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.araalicante.com\/#organization","name":"ARA | Asociaci\u00f3n de Restaurantes Alicante","url":"https:\/\/www.araalicante.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.araalicante.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.araalicante.com\/wp-content\/uploads\/2023\/09\/logoara.png","contentUrl":"https:\/\/www.araalicante.com\/wp-content\/uploads\/2023\/09\/logoara.png","width":400,"height":85,"caption":"ARA | Asociaci\u00f3n de Restaurantes Alicante"},"image":{"@id":"https:\/\/www.araalicante.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Ararestaurantesalicante","https:\/\/www.instagram.com\/ararestaurantesalicante\/"]},{"@type":"Person","@id":"https:\/\/www.araalicante.com\/#\/schema\/person\/e812fee62b3ce0c0ebca64fd5be08d67","name":"Maria Jose Anguita Garc\u00eda","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/717304dec3288ef41af7c91b6a8cecd0c5ac16a99dc419d6a059e8ac1557c4de?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/717304dec3288ef41af7c91b6a8cecd0c5ac16a99dc419d6a059e8ac1557c4de?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/717304dec3288ef41af7c91b6a8cecd0c5ac16a99dc419d6a059e8ac1557c4de?s=96&d=mm&r=g","caption":"Maria Jose Anguita Garc\u00eda"},"url":"https:\/\/www.araalicante.com\/en\/author\/maria-jose\/"}]}},"_links":{"self":[{"href":"https:\/\/www.araalicante.com\/en\/wp-json\/wp\/v2\/posts\/2878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.araalicante.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.araalicante.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.araalicante.com\/en\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.araalicante.com\/en\/wp-json\/wp\/v2\/comments?post=2878"}],"version-history":[{"count":6,"href":"https:\/\/www.araalicante.com\/en\/wp-json\/wp\/v2\/posts\/2878\/revisions"}],"predecessor-version":[{"id":3541,"href":"https:\/\/www.araalicante.com\/en\/wp-json\/wp\/v2\/posts\/2878\/revisions\/3541"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.araalicante.com\/en\/wp-json\/wp\/v2\/media\/2879"}],"wp:attachment":[{"href":"https:\/\/www.araalicante.com\/en\/wp-json\/wp\/v2\/media?parent=2878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.araalicante.com\/en\/wp-json\/wp\/v2\/categories?post=2878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.araalicante.com\/en\/wp-json\/wp\/v2\/tags?post=2878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}